{"id":15725,"date":"2025-04-28T17:59:29","date_gmt":"2025-04-28T15:59:29","guid":{"rendered":"https:\/\/soderep-ecans.numeria.dev\/fiches-techniques\/s300_ft01-2\/"},"modified":"2025-04-28T17:59:29","modified_gmt":"2025-04-28T15:59:29","slug":"s300_ft01-2","status":"publish","type":"se_fiches","link":"https:\/\/www.soderep-ecans.com\/en\/fiches-techniques\/s300_ft01-2\/","title":{"rendered":"S300_FT01"},"content":{"rendered":"<p>Metallic &#8211; M12 or M14 studs &#8211; IP65 &#8211;  Similar description: battery master switch, battery switch, battery cut off switch, battery disconnect switch, battery main switch, master disconnect, battery disconnector, SPDS<\/p>\n","protected":false},"author":1,"featured_media":12528,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-15725","se_fiches","type-se_fiches","status-publish","has-post-thumbnail"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>S300_FT01 - SODEREP-ECANS<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.soderep-ecans.com\/en\/fiches-techniques\/s300_ft01-2\/\" \/>\r\n<meta property=\"og:locale\" content=\"en_US\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"S300_FT01 - SODEREP-ECANS\" \/>\r\n<meta property=\"og:description\" content=\"Metallic &#8211; M12 or M14 studs &#8211; IP65 &#8211; Similar description: battery master switch, battery switch, battery cut off switch, battery disconnect switch, battery main switch, master disconnect, battery disconnector,...\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.soderep-ecans.com\/en\/fiches-techniques\/s300_ft01-2\/\" \/>\r\n<meta property=\"og:site_name\" content=\"SODEREP-ECANS\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.soderep-ecans.com\\\/en\\\/fiches-techniques\\\/s300_ft01-2\\\/\",\"url\":\"https:\\\/\\\/www.soderep-ecans.com\\\/en\\\/fiches-techniques\\\/s300_ft01-2\\\/\",\"name\":\"S300_FT01 - SODEREP-ECANS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.soderep-ecans.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.soderep-ecans.com\\\/en\\\/fiches-techniques\\\/s300_ft01-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.soderep-ecans.com\\\/en\\\/fiches-techniques\\\/s300_ft01-2\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2025-04-28T15:59:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.soderep-ecans.com\\\/en\\\/fiches-techniques\\\/s300_ft01-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.soderep-ecans.com\\\/en\\\/fiches-techniques\\\/s300_ft01-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.soderep-ecans.com\\\/en\\\/fiches-techniques\\\/s300_ft01-2\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.soderep-ecans.com\\\/en\\\/fiches-techniques\\\/s300_ft01-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.soderep-ecans.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiches techniques\",\"item\":\"https:\\\/\\\/www.soderep-ecans.com\\\/en\\\/fiches-techniques\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"S300_FT01\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.soderep-ecans.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.soderep-ecans.com\\\/en\\\/\",\"name\":\"Soderep-Ecans\",\"description\":\"BUILT FOR SAFETY\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.soderep-ecans.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.soderep-ecans.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.soderep-ecans.com\\\/en\\\/#organization\",\"name\":\"Soderep-Ecans\",\"url\":\"https:\\\/\\\/www.soderep-ecans.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.soderep-ecans.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.soderep-ecans.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/cropped-Favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.soderep-ecans.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/cropped-Favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Soderep-Ecans\"},\"image\":{\"@id\":\"https:\\\/\\\/www.soderep-ecans.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S300_FT01 - SODEREP-ECANS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.soderep-ecans.com\/en\/fiches-techniques\/s300_ft01-2\/","og_locale":"en_US","og_type":"article","og_title":"S300_FT01 - SODEREP-ECANS","og_description":"Metallic &#8211; M12 or M14 studs &#8211; IP65 &#8211; Similar description: battery master switch, battery switch, battery cut off switch, battery disconnect switch, battery main switch, master disconnect, battery disconnector,...","og_url":"https:\/\/www.soderep-ecans.com\/en\/fiches-techniques\/s300_ft01-2\/","og_site_name":"SODEREP-ECANS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.soderep-ecans.com\/en\/fiches-techniques\/s300_ft01-2\/","url":"https:\/\/www.soderep-ecans.com\/en\/fiches-techniques\/s300_ft01-2\/","name":"S300_FT01 - SODEREP-ECANS","isPartOf":{"@id":"https:\/\/www.soderep-ecans.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.soderep-ecans.com\/en\/fiches-techniques\/s300_ft01-2\/#primaryimage"},"image":{"@id":"https:\/\/www.soderep-ecans.com\/en\/fiches-techniques\/s300_ft01-2\/#primaryimage"},"thumbnailUrl":"","datePublished":"2025-04-28T15:59:29+00:00","breadcrumb":{"@id":"https:\/\/www.soderep-ecans.com\/en\/fiches-techniques\/s300_ft01-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.soderep-ecans.com\/en\/fiches-techniques\/s300_ft01-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.soderep-ecans.com\/en\/fiches-techniques\/s300_ft01-2\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/www.soderep-ecans.com\/en\/fiches-techniques\/s300_ft01-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.soderep-ecans.com\/en\/"},{"@type":"ListItem","position":2,"name":"Fiches techniques","item":"https:\/\/www.soderep-ecans.com\/en\/fiches-techniques\/"},{"@type":"ListItem","position":3,"name":"S300_FT01"}]},{"@type":"WebSite","@id":"https:\/\/www.soderep-ecans.com\/en\/#website","url":"https:\/\/www.soderep-ecans.com\/en\/","name":"Soderep-Ecans","description":"BUILT FOR SAFETY","publisher":{"@id":"https:\/\/www.soderep-ecans.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.soderep-ecans.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.soderep-ecans.com\/en\/#organization","name":"Soderep-Ecans","url":"https:\/\/www.soderep-ecans.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.soderep-ecans.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.soderep-ecans.com\/wp-content\/uploads\/2022\/10\/cropped-Favicon.png","contentUrl":"https:\/\/www.soderep-ecans.com\/wp-content\/uploads\/2022\/10\/cropped-Favicon.png","width":512,"height":512,"caption":"Soderep-Ecans"},"image":{"@id":"https:\/\/www.soderep-ecans.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.soderep-ecans.com\/en\/wp-json\/wp\/v2\/se_fiches\/15725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.soderep-ecans.com\/en\/wp-json\/wp\/v2\/se_fiches"}],"about":[{"href":"https:\/\/www.soderep-ecans.com\/en\/wp-json\/wp\/v2\/types\/se_fiches"}],"author":[{"embeddable":true,"href":"https:\/\/www.soderep-ecans.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/www.soderep-ecans.com\/en\/wp-json\/wp\/v2\/se_fiches\/15725\/revisions"}],"predecessor-version":[{"id":15842,"href":"https:\/\/www.soderep-ecans.com\/en\/wp-json\/wp\/v2\/se_fiches\/15725\/revisions\/15842"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.soderep-ecans.com\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.soderep-ecans.com\/en\/wp-json\/wp\/v2\/media?parent=15725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}